{"id":891,"count":1,"description":"","link":"https:\/\/www.autolexicon.net\/cs\/articles\/tag\/oslneni\/","name":"osln\u011bn\u00ed","slug":"oslneni","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>osln\u011bn\u00ed Archivy - autolexicon.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.autolexicon.net\/cs\/articles\/tag\/oslneni\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"osln\u011bn\u00ed Archivy - autolexicon.net\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.autolexicon.net\/cs\/articles\/tag\/oslneni\/\" \/>\n<meta property=\"og:site_name\" content=\"autolexicon.net\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@autolexiconnet\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/cs\\\/articles\\\/tag\\\/oslneni\\\/\",\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/cs\\\/articles\\\/tag\\\/oslneni\\\/\",\"name\":\"osln\u011bn\u00ed Archivy - autolexicon.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/cs\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/cs\\\/articles\\\/tag\\\/oslneni\\\/#breadcrumb\"},\"inLanguage\":\"cs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/cs\\\/articles\\\/tag\\\/oslneni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\\\/\\\/www.autolexicon.net\\\/cs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"osln\u011bn\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/cs\\\/#website\",\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/cs\\\/\",\"name\":\"autolexicon.net\",\"description\":\"...  s nami uvid\u00edte pod kapotu\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/cs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.autolexicon.net\\\/cs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/cs\\\/#organization\",\"name\":\"autolexicon.net\",\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/cs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/cs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/obr_clanky\\\/2024_logo___330x90px-2.png\",\"contentUrl\":\"https:\\\/\\\/www.autolexicon.net\\\/obr_clanky\\\/2024_logo___330x90px-2.png\",\"width\":328,\"height\":90,\"caption\":\"autolexicon.net\"},\"image\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/cs\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/autolexicon.net\",\"https:\\\/\\\/x.com\\\/autolexiconnet\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"osln\u011bn\u00ed Archivy - autolexicon.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.autolexicon.net\/cs\/articles\/tag\/oslneni\/","og_locale":"cs_CZ","og_type":"article","og_title":"osln\u011bn\u00ed Archivy - autolexicon.net","og_url":"https:\/\/www.autolexicon.net\/cs\/articles\/tag\/oslneni\/","og_site_name":"autolexicon.net","twitter_card":"summary_large_image","twitter_site":"@autolexiconnet","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.autolexicon.net\/cs\/articles\/tag\/oslneni\/","url":"https:\/\/www.autolexicon.net\/cs\/articles\/tag\/oslneni\/","name":"osln\u011bn\u00ed Archivy - autolexicon.net","isPartOf":{"@id":"https:\/\/www.autolexicon.net\/cs\/#website"},"breadcrumb":{"@id":"https:\/\/www.autolexicon.net\/cs\/articles\/tag\/oslneni\/#breadcrumb"},"inLanguage":"cs"},{"@type":"BreadcrumbList","@id":"https:\/\/www.autolexicon.net\/cs\/articles\/tag\/oslneni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/www.autolexicon.net\/cs\/"},{"@type":"ListItem","position":2,"name":"osln\u011bn\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/www.autolexicon.net\/cs\/#website","url":"https:\/\/www.autolexicon.net\/cs\/","name":"autolexicon.net","description":"...  s nami uvid\u00edte pod kapotu","publisher":{"@id":"https:\/\/www.autolexicon.net\/cs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.autolexicon.net\/cs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/www.autolexicon.net\/cs\/#organization","name":"autolexicon.net","url":"https:\/\/www.autolexicon.net\/cs\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/www.autolexicon.net\/cs\/#\/schema\/logo\/image\/","url":"https:\/\/www.autolexicon.net\/obr_clanky\/2024_logo___330x90px-2.png","contentUrl":"https:\/\/www.autolexicon.net\/obr_clanky\/2024_logo___330x90px-2.png","width":328,"height":90,"caption":"autolexicon.net"},"image":{"@id":"https:\/\/www.autolexicon.net\/cs\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/autolexicon.net","https:\/\/x.com\/autolexiconnet"]}]}},"_links":{"self":[{"href":"https:\/\/www.autolexicon.net\/cs\/wp-json\/wp\/v2\/tags\/891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.autolexicon.net\/cs\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.autolexicon.net\/cs\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.autolexicon.net\/cs\/wp-json\/wp\/v2\/posts?tags=891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}