{"id":2171,"date":"2011-04-04T07:42:33","date_gmt":"2011-04-04T07:42:33","guid":{"rendered":"http:\/\/wordpress.autolexicon.net\/?p=2171"},"modified":"2016-06-30T20:15:32","modified_gmt":"2016-06-30T20:15:32","slug":"diesotto-dieselovy-motor-na-benzin","status":"publish","type":"post","link":"https:\/\/www.autolexicon.net\/en\/articles\/diesotto-dieselovy-motor-na-benzin\/","title":{"rendered":"DiesOtto \u2013 dieselov\u00fd motor na benz\u00edn"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.autolexicon.net\/cs\/wp-json\/wp\/v2\/posts\/2171\" class=\"qtranxs-available-language-link qtranxs-available-language-link-cs\" title=\"\u010cesky\">\u010cesky<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Vzn\u011btov\u00fd motor spaluj\u00edc\u00ed benz\u00edn? Co je to za nesmysl? Klasick\u00fd vzn\u011btov\u00fd motor by se po natankov\u00e1n\u00ed benz\u00ednu do palivov\u00e9 n\u00e1dr\u017ee zad\u0159el. Ne tak nov\u00fd motor od Mercedesu. Mercedes Benz vyvinul spole\u010dn\u011b se spole\u010dnost\u00ed Ricardo nov\u00fd motor spojuj\u00edc\u00ed p\u0159ednosti vzn\u011btov\u00fdch a z\u00e1\u017eehov\u00fdch motor\u016f. Tento nov\u00fd motor konstrukt\u00e9\u0159i nazvali p\u0159\u00edhodn\u011b DiesOtto, co\u017e je spojenina slov Diesel a Otto.<\/p>\n","protected":false},"author":1,"featured_media":1051,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10217573569066608_119527941460186":"","twitter_308591058_308591058":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","ngg_post_thumbnail":0,"two_page_speed":[],"footnotes":""},"categories":[1,8,28,29,4],"tags":[354,358,282,289,189,357,356,307,355],"class_list":["post-2171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nezarazene","category-hnaci-ustroji","category-technicke-zajimavosti","category-zkratky-a-pojmy","category-casti-automobilu","tag-diesotto","tag-benzin","tag-diesel","tag-hybrid","tag-motor","tag-spalovani-benzinu","tag-spalovani-nafty","tag-vznetovy-motor","tag-zazehovy-motor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DiesOtto \u2013 dieselov\u00fd motor na benz\u00edn - autolexicon.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.autolexicon.net\/en\/articles\/diesotto-dieselovy-motor-na-benzin\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DiesOtto \u2013 dieselov\u00fd motor na benz\u00edn - autolexicon.net\" \/>\n<meta property=\"og:description\" content=\"Vzn\u011btov\u00fd motor spaluj\u00edc\u00ed benz\u00edn? Co je to za nesmysl? Klasick\u00fd vzn\u011btov\u00fd motor by se po natankov\u00e1n\u00ed benz\u00ednu do palivov\u00e9 n\u00e1dr\u017ee zad\u0159el. Ne tak nov\u00fd motor od Mercedesu. Mercedes Benz vyvinul spole\u010dn\u011b se spole\u010dnost\u00ed Ricardo nov\u00fd motor spojuj\u00edc\u00ed p\u0159ednosti vzn\u011btov\u00fdch a z\u00e1\u017eehov\u00fdch motor\u016f. Tento nov\u00fd motor konstrukt\u00e9\u0159i nazvali p\u0159\u00edhodn\u011b DiesOtto, co\u017e je spojenina slov Diesel a Otto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.autolexicon.net\/en\/articles\/diesotto-dieselovy-motor-na-benzin\/\" \/>\n<meta property=\"og:site_name\" content=\"autolexicon.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/autolexicon.net\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-04T07:42:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-30T20:15:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.autolexicon.net\/obr_clanky\/cs_diesotto_001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"302\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ing. Jan Sajdl, Ph.D.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@autolexiconnet\" \/>\n<meta name=\"twitter:site\" content=\"@autolexiconnet\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ing. Jan Sajdl, Ph.D.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/articles\\\/diesotto-dieselovy-motor-na-benzin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/articles\\\/diesotto-dieselovy-motor-na-benzin\\\/\"},\"author\":{\"name\":\"Ing. Jan Sajdl, Ph.D.\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/de\\\/#\\\/schema\\\/person\\\/feba94e934e2110b3fa58a851f9bf0e5\"},\"headline\":\"DiesOtto \u2013 dieselov\u00fd motor na benz\u00edn\",\"datePublished\":\"2011-04-04T07:42:33+00:00\",\"dateModified\":\"2016-06-30T20:15:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/articles\\\/diesotto-dieselovy-motor-na-benzin\\\/\"},\"wordCount\":447,\"publisher\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/articles\\\/diesotto-dieselovy-motor-na-benzin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.autolexicon.net\\\/obr_clanky\\\/cs_diesotto_001.jpg\",\"keywords\":[\"Diesotto\",\"benz\u00edn\",\"diesel\",\"hybrid\",\"engine\",\"spalov\u00e1n\u00ed benz\u00ednu\",\"spalov\u00e1n\u00ed nafty\",\"vzn\u011btov\u00fd motor\",\"z\u00e1\u017eehov\u00fd motor\"],\"articleSection\":[\"=== All ===\",\"Drivetrain\",\"Technical highlights\",\"Abbreviations and terms\",\"Car parts\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/articles\\\/diesotto-dieselovy-motor-na-benzin\\\/\",\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/articles\\\/diesotto-dieselovy-motor-na-benzin\\\/\",\"name\":\"DiesOtto \u2013 dieselov\u00fd motor na benz\u00edn - autolexicon.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/articles\\\/diesotto-dieselovy-motor-na-benzin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/articles\\\/diesotto-dieselovy-motor-na-benzin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.autolexicon.net\\\/obr_clanky\\\/cs_diesotto_001.jpg\",\"datePublished\":\"2011-04-04T07:42:33+00:00\",\"dateModified\":\"2016-06-30T20:15:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/articles\\\/diesotto-dieselovy-motor-na-benzin\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/articles\\\/diesotto-dieselovy-motor-na-benzin\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/articles\\\/diesotto-dieselovy-motor-na-benzin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/obr_clanky\\\/cs_diesotto_001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.autolexicon.net\\\/obr_clanky\\\/cs_diesotto_001.jpg\",\"width\":\"555\",\"height\":\"302\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/articles\\\/diesotto-dieselovy-motor-na-benzin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DiesOtto \u2013 dieselov\u00fd motor na benz\u00edn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/\",\"name\":\"autolexicon.net\",\"description\":\"... with us you will see under the hood\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/#organization\",\"name\":\"autolexicon.net\",\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/obr_clanky\\\/2024_logo___330x90px-2.png\",\"contentUrl\":\"https:\\\/\\\/www.autolexicon.net\\\/obr_clanky\\\/2024_logo___330x90px-2.png\",\"width\":328,\"height\":90,\"caption\":\"autolexicon.net\"},\"image\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/autolexicon.net\",\"https:\\\/\\\/x.com\\\/autolexiconnet\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/de\\\/#\\\/schema\\\/person\\\/feba94e934e2110b3fa58a851f9bf0e5\",\"name\":\"Ing. Jan Sajdl, Ph.D.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70f1c2597d36a3d134d5e6f00bf72449593f8da593deacce372fe943f7708d0b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70f1c2597d36a3d134d5e6f00bf72449593f8da593deacce372fe943f7708d0b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70f1c2597d36a3d134d5e6f00bf72449593f8da593deacce372fe943f7708d0b?s=96&d=mm&r=g\",\"caption\":\"Ing. Jan Sajdl, Ph.D.\"},\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/en\\\/articles\\\/author\\\/rebel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DiesOtto \u2013 dieselov\u00fd motor na benz\u00edn - autolexicon.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.autolexicon.net\/en\/articles\/diesotto-dieselovy-motor-na-benzin\/","og_locale":"en_US","og_type":"article","og_title":"DiesOtto \u2013 dieselov\u00fd motor na benz\u00edn - autolexicon.net","og_description":"Vzn\u011btov\u00fd motor spaluj\u00edc\u00ed benz\u00edn? Co je to za nesmysl? Klasick\u00fd vzn\u011btov\u00fd motor by se po natankov\u00e1n\u00ed benz\u00ednu do palivov\u00e9 n\u00e1dr\u017ee zad\u0159el. Ne tak nov\u00fd motor od Mercedesu. Mercedes Benz vyvinul spole\u010dn\u011b se spole\u010dnost\u00ed Ricardo nov\u00fd motor spojuj\u00edc\u00ed p\u0159ednosti vzn\u011btov\u00fdch a z\u00e1\u017eehov\u00fdch motor\u016f. Tento nov\u00fd motor konstrukt\u00e9\u0159i nazvali p\u0159\u00edhodn\u011b DiesOtto, co\u017e je spojenina slov Diesel a Otto.","og_url":"https:\/\/www.autolexicon.net\/en\/articles\/diesotto-dieselovy-motor-na-benzin\/","og_site_name":"autolexicon.net","article_publisher":"https:\/\/www.facebook.com\/autolexicon.net","article_published_time":"2011-04-04T07:42:33+00:00","article_modified_time":"2016-06-30T20:15:32+00:00","og_image":[{"width":555,"height":302,"url":"https:\/\/www.autolexicon.net\/obr_clanky\/cs_diesotto_001.jpg","type":"image\/jpeg"}],"author":"Ing. Jan Sajdl, Ph.D.","twitter_card":"summary_large_image","twitter_creator":"@autolexiconnet","twitter_site":"@autolexiconnet","twitter_misc":{"Written by":"Ing. Jan Sajdl, Ph.D.","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.autolexicon.net\/articles\/diesotto-dieselovy-motor-na-benzin\/#article","isPartOf":{"@id":"https:\/\/www.autolexicon.net\/articles\/diesotto-dieselovy-motor-na-benzin\/"},"author":{"name":"Ing. Jan Sajdl, Ph.D.","@id":"https:\/\/www.autolexicon.net\/de\/#\/schema\/person\/feba94e934e2110b3fa58a851f9bf0e5"},"headline":"DiesOtto \u2013 dieselov\u00fd motor na benz\u00edn","datePublished":"2011-04-04T07:42:33+00:00","dateModified":"2016-06-30T20:15:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.autolexicon.net\/articles\/diesotto-dieselovy-motor-na-benzin\/"},"wordCount":447,"publisher":{"@id":"https:\/\/www.autolexicon.net\/de\/#organization"},"image":{"@id":"https:\/\/www.autolexicon.net\/articles\/diesotto-dieselovy-motor-na-benzin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.autolexicon.net\/obr_clanky\/cs_diesotto_001.jpg","keywords":["Diesotto","benz\u00edn","diesel","hybrid","engine","spalov\u00e1n\u00ed benz\u00ednu","spalov\u00e1n\u00ed nafty","vzn\u011btov\u00fd motor","z\u00e1\u017eehov\u00fd motor"],"articleSection":["=== All ===","Drivetrain","Technical highlights","Abbreviations and terms","Car parts"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.autolexicon.net\/en\/articles\/diesotto-dieselovy-motor-na-benzin\/","url":"https:\/\/www.autolexicon.net\/en\/articles\/diesotto-dieselovy-motor-na-benzin\/","name":"DiesOtto \u2013 dieselov\u00fd motor na benz\u00edn - autolexicon.net","isPartOf":{"@id":"https:\/\/www.autolexicon.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.autolexicon.net\/en\/articles\/diesotto-dieselovy-motor-na-benzin\/#primaryimage"},"image":{"@id":"https:\/\/www.autolexicon.net\/articles\/diesotto-dieselovy-motor-na-benzin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.autolexicon.net\/obr_clanky\/cs_diesotto_001.jpg","datePublished":"2011-04-04T07:42:33+00:00","dateModified":"2016-06-30T20:15:32+00:00","breadcrumb":{"@id":"https:\/\/www.autolexicon.net\/en\/articles\/diesotto-dieselovy-motor-na-benzin\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/www.autolexicon.net\/en\/articles\/diesotto-dieselovy-motor-na-benzin\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.autolexicon.net\/en\/articles\/diesotto-dieselovy-motor-na-benzin\/#primaryimage","url":"https:\/\/www.autolexicon.net\/obr_clanky\/cs_diesotto_001.jpg","contentUrl":"https:\/\/www.autolexicon.net\/obr_clanky\/cs_diesotto_001.jpg","width":"555","height":"302"},{"@type":"BreadcrumbList","@id":"https:\/\/www.autolexicon.net\/en\/articles\/diesotto-dieselovy-motor-na-benzin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/www.autolexicon.net\/en\/"},{"@type":"ListItem","position":2,"name":"DiesOtto \u2013 dieselov\u00fd motor na benz\u00edn"}]},{"@type":"WebSite","@id":"https:\/\/www.autolexicon.net\/en\/#website","url":"https:\/\/www.autolexicon.net\/en\/","name":"autolexicon.net","description":"... with us you will see under the hood","publisher":{"@id":"https:\/\/www.autolexicon.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.autolexicon.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.autolexicon.net\/en\/#organization","name":"autolexicon.net","url":"https:\/\/www.autolexicon.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.autolexicon.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.autolexicon.net\/obr_clanky\/2024_logo___330x90px-2.png","contentUrl":"https:\/\/www.autolexicon.net\/obr_clanky\/2024_logo___330x90px-2.png","width":328,"height":90,"caption":"autolexicon.net"},"image":{"@id":"https:\/\/www.autolexicon.net\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/autolexicon.net","https:\/\/x.com\/autolexiconnet"]},{"@type":"Person","@id":"https:\/\/www.autolexicon.net\/de\/#\/schema\/person\/feba94e934e2110b3fa58a851f9bf0e5","name":"Ing. Jan Sajdl, Ph.D.","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/70f1c2597d36a3d134d5e6f00bf72449593f8da593deacce372fe943f7708d0b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/70f1c2597d36a3d134d5e6f00bf72449593f8da593deacce372fe943f7708d0b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/70f1c2597d36a3d134d5e6f00bf72449593f8da593deacce372fe943f7708d0b?s=96&d=mm&r=g","caption":"Ing. Jan Sajdl, Ph.D."},"url":"https:\/\/www.autolexicon.net\/en\/articles\/author\/rebel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.autolexicon.net\/en\/wp-json\/wp\/v2\/posts\/2171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.autolexicon.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.autolexicon.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.autolexicon.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.autolexicon.net\/en\/wp-json\/wp\/v2\/comments?post=2171"}],"version-history":[{"count":0,"href":"https:\/\/www.autolexicon.net\/en\/wp-json\/wp\/v2\/posts\/2171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.autolexicon.net\/en\/wp-json\/wp\/v2\/media\/1051"}],"wp:attachment":[{"href":"https:\/\/www.autolexicon.net\/en\/wp-json\/wp\/v2\/media?parent=2171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.autolexicon.net\/en\/wp-json\/wp\/v2\/categories?post=2171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.autolexicon.net\/en\/wp-json\/wp\/v2\/tags?post=2171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}