{"id":1915,"date":"2011-03-31T09:55:31","date_gmt":"2011-03-31T09:55:31","guid":{"rendered":"http:\/\/wordpress.autolexicon.net\/?p=1915"},"modified":"2021-01-25T20:38:25","modified_gmt":"2021-01-25T20:38:25","slug":"cadillac-one","status":"publish","type":"post","link":"https:\/\/www.autolexicon.net\/sk\/articles\/cadillac-one\/","title":{"rendered":"Cadillac One"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-sk\">Tento pr\u00edspevok nie je dostupn\u00fd v slovenskom jazyku. Dostupn\u00e9 jazyky s\u00fa: <a href=\"https:\/\/www.autolexicon.net\/cs\/wp-json\/wp\/v2\/posts\/1915\" class=\"qtranxs-available-language-link qtranxs-available-language-link-cs\" title=\"\u010cesky\">\u010cesky<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cadillac One je pravd\u011bpodobn\u011b nejbezpe\u010dn\u011bj\u0161\u00ed automobil sv\u011bta. U\u017e\u00edv\u00e1 ho americk\u00fd prezident, kter\u00fd si tuto limuz\u00ednu voz\u00ed s sebou po cel\u00e9m sv\u011bt\u011b. V prezidentsk\u00e9 kolon\u011b jedou v\u017edy dv\u011b identick\u00e9 limuz\u00edny, aby zm\u00e1tli p\u0159\u00edpadn\u00e9 \u00fato\u010dn\u00edky.<\/p>\n","protected":false},"author":1,"featured_media":968,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10217573569066608_119527941460186":"","twitter_308591058_308591058":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","ngg_post_thumbnail":0,"two_page_speed":[],"footnotes":""},"categories":[1,3,28,29],"tags":[253,254,256,255],"class_list":["post-1915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nezarazene","category-bezpecnost","category-technicke-zajimavosti","category-zkratky-a-pojmy","tag-cadillac-one","tag-nejbezpecnejsi-vuz","tag-prezidentska-limuzina","tag-prezidentsky-automobil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cadillac One - autolexicon.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.autolexicon.net\/sk\/articles\/cadillac-one\/\" \/>\n<meta property=\"og:locale\" content=\"sk_SK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cadillac One - autolexicon.net\" \/>\n<meta property=\"og:description\" content=\"Cadillac One je pravd\u011bpodobn\u011b nejbezpe\u010dn\u011bj\u0161\u00ed automobil sv\u011bta. U\u017e\u00edv\u00e1 ho americk\u00fd prezident, kter\u00fd si tuto limuz\u00ednu voz\u00ed s sebou po cel\u00e9m sv\u011bt\u011b. V prezidentsk\u00e9 kolon\u011b jedou v\u017edy dv\u011b identick\u00e9 limuz\u00edny, aby zm\u00e1tli p\u0159\u00edpadn\u00e9 \u00fato\u010dn\u00edky.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.autolexicon.net\/sk\/articles\/cadillac-one\/\" \/>\n<meta property=\"og:site_name\" content=\"autolexicon.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/autolexicon.net\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-31T09:55:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-25T20:38:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.autolexicon.net\/obr_clanky\/cs_cadillac_one_02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"339\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ing. Jan Sajdl, Ph.D.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@autolexiconnet\" \/>\n<meta name=\"twitter:site\" content=\"@autolexiconnet\" \/>\n<meta name=\"twitter:label1\" content=\"Autor\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ing. Jan Sajdl, Ph.D.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Predpokladan\u00fd \u010das \u010d\u00edtania\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 min\u00faty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/articles\\\/cadillac-one\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/articles\\\/cadillac-one\\\/\"},\"author\":{\"name\":\"Ing. Jan Sajdl, Ph.D.\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/de\\\/#\\\/schema\\\/person\\\/feba94e934e2110b3fa58a851f9bf0e5\"},\"headline\":\"Cadillac One\",\"datePublished\":\"2011-03-31T09:55:31+00:00\",\"dateModified\":\"2021-01-25T20:38:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/articles\\\/cadillac-one\\\/\"},\"wordCount\":865,\"publisher\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/articles\\\/cadillac-one\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.autolexicon.net\\\/obr_clanky\\\/cs_cadillac_one_02.jpg\",\"keywords\":[\"Cadillac One\",\"nejbezpe\u010dn\u011bj\u0161\u00ed v\u016fz\",\"prezidentsk\u00e1 limuz\u00edna\",\"prezidentsk\u00fd automobil\"],\"articleSection\":[\"=== V\u0161etko ===\",\"Bezpe\u010dnos\u0165\",\"Technick\u00e9 zauj\u00edmavosti\",\"Skratky a pojmy\"],\"inLanguage\":\"sk-SK\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/articles\\\/cadillac-one\\\/\",\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/articles\\\/cadillac-one\\\/\",\"name\":\"Cadillac One - autolexicon.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/articles\\\/cadillac-one\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/articles\\\/cadillac-one\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.autolexicon.net\\\/obr_clanky\\\/cs_cadillac_one_02.jpg\",\"datePublished\":\"2011-03-31T09:55:31+00:00\",\"dateModified\":\"2021-01-25T20:38:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/articles\\\/cadillac-one\\\/#breadcrumb\"},\"inLanguage\":\"sk-SK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/articles\\\/cadillac-one\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sk-SK\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/articles\\\/cadillac-one\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/obr_clanky\\\/cs_cadillac_one_02.jpg\",\"contentUrl\":\"https:\\\/\\\/www.autolexicon.net\\\/obr_clanky\\\/cs_cadillac_one_02.jpg\",\"width\":\"580\",\"height\":\"339\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/articles\\\/cadillac-one\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cadillac One\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/#website\",\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/\",\"name\":\"autolexicon.net\",\"description\":\"... s nami uvid\u00edte pod kapotu\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sk-SK\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/#organization\",\"name\":\"autolexicon.net\",\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sk-SK\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/obr_clanky\\\/2024_logo___330x90px-2.png\",\"contentUrl\":\"https:\\\/\\\/www.autolexicon.net\\\/obr_clanky\\\/2024_logo___330x90px-2.png\",\"width\":328,\"height\":90,\"caption\":\"autolexicon.net\"},\"image\":{\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/autolexicon.net\",\"https:\\\/\\\/x.com\\\/autolexiconnet\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.autolexicon.net\\\/de\\\/#\\\/schema\\\/person\\\/feba94e934e2110b3fa58a851f9bf0e5\",\"name\":\"Ing. Jan Sajdl, Ph.D.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sk-SK\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70f1c2597d36a3d134d5e6f00bf72449593f8da593deacce372fe943f7708d0b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70f1c2597d36a3d134d5e6f00bf72449593f8da593deacce372fe943f7708d0b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70f1c2597d36a3d134d5e6f00bf72449593f8da593deacce372fe943f7708d0b?s=96&d=mm&r=g\",\"caption\":\"Ing. Jan Sajdl, Ph.D.\"},\"url\":\"https:\\\/\\\/www.autolexicon.net\\\/sk\\\/articles\\\/author\\\/rebel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cadillac One - autolexicon.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.autolexicon.net\/sk\/articles\/cadillac-one\/","og_locale":"sk_SK","og_type":"article","og_title":"Cadillac One - autolexicon.net","og_description":"Cadillac One je pravd\u011bpodobn\u011b nejbezpe\u010dn\u011bj\u0161\u00ed automobil sv\u011bta. U\u017e\u00edv\u00e1 ho americk\u00fd prezident, kter\u00fd si tuto limuz\u00ednu voz\u00ed s sebou po cel\u00e9m sv\u011bt\u011b. V prezidentsk\u00e9 kolon\u011b jedou v\u017edy dv\u011b identick\u00e9 limuz\u00edny, aby zm\u00e1tli p\u0159\u00edpadn\u00e9 \u00fato\u010dn\u00edky.","og_url":"https:\/\/www.autolexicon.net\/sk\/articles\/cadillac-one\/","og_site_name":"autolexicon.net","article_publisher":"https:\/\/www.facebook.com\/autolexicon.net","article_published_time":"2011-03-31T09:55:31+00:00","article_modified_time":"2021-01-25T20:38:25+00:00","og_image":[{"width":580,"height":339,"url":"https:\/\/www.autolexicon.net\/obr_clanky\/cs_cadillac_one_02.jpg","type":"image\/jpeg"}],"author":"Ing. Jan Sajdl, Ph.D.","twitter_card":"summary_large_image","twitter_creator":"@autolexiconnet","twitter_site":"@autolexiconnet","twitter_misc":{"Autor":"Ing. Jan Sajdl, Ph.D.","Predpokladan\u00fd \u010das \u010d\u00edtania":"4 min\u00faty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.autolexicon.net\/articles\/cadillac-one\/#article","isPartOf":{"@id":"https:\/\/www.autolexicon.net\/articles\/cadillac-one\/"},"author":{"name":"Ing. Jan Sajdl, Ph.D.","@id":"https:\/\/www.autolexicon.net\/de\/#\/schema\/person\/feba94e934e2110b3fa58a851f9bf0e5"},"headline":"Cadillac One","datePublished":"2011-03-31T09:55:31+00:00","dateModified":"2021-01-25T20:38:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.autolexicon.net\/articles\/cadillac-one\/"},"wordCount":865,"publisher":{"@id":"https:\/\/www.autolexicon.net\/de\/#organization"},"image":{"@id":"https:\/\/www.autolexicon.net\/articles\/cadillac-one\/#primaryimage"},"thumbnailUrl":"https:\/\/www.autolexicon.net\/obr_clanky\/cs_cadillac_one_02.jpg","keywords":["Cadillac One","nejbezpe\u010dn\u011bj\u0161\u00ed v\u016fz","prezidentsk\u00e1 limuz\u00edna","prezidentsk\u00fd automobil"],"articleSection":["=== V\u0161etko ===","Bezpe\u010dnos\u0165","Technick\u00e9 zauj\u00edmavosti","Skratky a pojmy"],"inLanguage":"sk-SK"},{"@type":"WebPage","@id":"https:\/\/www.autolexicon.net\/sk\/articles\/cadillac-one\/","url":"https:\/\/www.autolexicon.net\/sk\/articles\/cadillac-one\/","name":"Cadillac One - autolexicon.net","isPartOf":{"@id":"https:\/\/www.autolexicon.net\/sk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.autolexicon.net\/sk\/articles\/cadillac-one\/#primaryimage"},"image":{"@id":"https:\/\/www.autolexicon.net\/articles\/cadillac-one\/#primaryimage"},"thumbnailUrl":"https:\/\/www.autolexicon.net\/obr_clanky\/cs_cadillac_one_02.jpg","datePublished":"2011-03-31T09:55:31+00:00","dateModified":"2021-01-25T20:38:25+00:00","breadcrumb":{"@id":"https:\/\/www.autolexicon.net\/sk\/articles\/cadillac-one\/#breadcrumb"},"inLanguage":"sk-SK","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/www.autolexicon.net\/sk\/articles\/cadillac-one\/"]]}]},{"@type":"ImageObject","inLanguage":"sk-SK","@id":"https:\/\/www.autolexicon.net\/sk\/articles\/cadillac-one\/#primaryimage","url":"https:\/\/www.autolexicon.net\/obr_clanky\/cs_cadillac_one_02.jpg","contentUrl":"https:\/\/www.autolexicon.net\/obr_clanky\/cs_cadillac_one_02.jpg","width":"580","height":"339"},{"@type":"BreadcrumbList","@id":"https:\/\/www.autolexicon.net\/sk\/articles\/cadillac-one\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/www.autolexicon.net\/sk\/"},{"@type":"ListItem","position":2,"name":"Cadillac One"}]},{"@type":"WebSite","@id":"https:\/\/www.autolexicon.net\/sk\/#website","url":"https:\/\/www.autolexicon.net\/sk\/","name":"autolexicon.net","description":"... s nami uvid\u00edte pod kapotu","publisher":{"@id":"https:\/\/www.autolexicon.net\/sk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.autolexicon.net\/sk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sk-SK"},{"@type":"Organization","@id":"https:\/\/www.autolexicon.net\/sk\/#organization","name":"autolexicon.net","url":"https:\/\/www.autolexicon.net\/sk\/","logo":{"@type":"ImageObject","inLanguage":"sk-SK","@id":"https:\/\/www.autolexicon.net\/sk\/#\/schema\/logo\/image\/","url":"https:\/\/www.autolexicon.net\/obr_clanky\/2024_logo___330x90px-2.png","contentUrl":"https:\/\/www.autolexicon.net\/obr_clanky\/2024_logo___330x90px-2.png","width":328,"height":90,"caption":"autolexicon.net"},"image":{"@id":"https:\/\/www.autolexicon.net\/sk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/autolexicon.net","https:\/\/x.com\/autolexiconnet"]},{"@type":"Person","@id":"https:\/\/www.autolexicon.net\/de\/#\/schema\/person\/feba94e934e2110b3fa58a851f9bf0e5","name":"Ing. Jan Sajdl, Ph.D.","image":{"@type":"ImageObject","inLanguage":"sk-SK","@id":"https:\/\/secure.gravatar.com\/avatar\/70f1c2597d36a3d134d5e6f00bf72449593f8da593deacce372fe943f7708d0b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/70f1c2597d36a3d134d5e6f00bf72449593f8da593deacce372fe943f7708d0b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/70f1c2597d36a3d134d5e6f00bf72449593f8da593deacce372fe943f7708d0b?s=96&d=mm&r=g","caption":"Ing. Jan Sajdl, Ph.D."},"url":"https:\/\/www.autolexicon.net\/sk\/articles\/author\/rebel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.autolexicon.net\/sk\/wp-json\/wp\/v2\/posts\/1915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.autolexicon.net\/sk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.autolexicon.net\/sk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.autolexicon.net\/sk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.autolexicon.net\/sk\/wp-json\/wp\/v2\/comments?post=1915"}],"version-history":[{"count":0,"href":"https:\/\/www.autolexicon.net\/sk\/wp-json\/wp\/v2\/posts\/1915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.autolexicon.net\/sk\/wp-json\/wp\/v2\/media\/968"}],"wp:attachment":[{"href":"https:\/\/www.autolexicon.net\/sk\/wp-json\/wp\/v2\/media?parent=1915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.autolexicon.net\/sk\/wp-json\/wp\/v2\/categories?post=1915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.autolexicon.net\/sk\/wp-json\/wp\/v2\/tags?post=1915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}